{"id":5499,"count":3,"description":"Sewing Machine Needles","link":"https:\/\/orduz-usa.com\/en\/categoria-producto\/repuestos-de-maquinas-de-coser\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\/","name":"Sewing Machine Needles","slug":"orduz-usa-com-product-category-sewing-machine-needles","taxonomy":"product_cat","parent":5357,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agujas para M\u00e1quinas de Coser Industriales | Orduz USA<\/title>\n<meta name=\"description\" content=\"Compra agujas para m\u00e1quinas de coser industriales y familiares en Miami. Agujas Singer, Juki, Brother y m\u00e1s con env\u00edos r\u00e1pidos en USA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orduz-usa.com\/en\/product-category\/sewing-machine-parts\/orduz-usa-com-product-category-sewing-machine-needles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agujas para M\u00e1quinas de Coser archivos\" \/>\n<meta property=\"og:description\" content=\"Compra agujas para m\u00e1quinas de coser industriales y familiares en Miami. Agujas Singer, Juki, Brother y m\u00e1s con env\u00edos r\u00e1pidos en USA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orduz-usa.com\/en\/product-category\/sewing-machine-parts\/orduz-usa-com-product-category-sewing-machine-needles\/\" \/>\n<meta property=\"og:site_name\" content=\"Orduz USA Maquinas de coser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/categoria-producto\\\/repuestos-de-maquinas-de-coser\\\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\\\/\",\"url\":\"https:\\\/\\\/orduz-usa.com\\\/categoria-producto\\\/repuestos-de-maquinas-de-coser\\\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\\\/\",\"name\":\"Agujas para M\u00e1quinas de Coser Industriales | Orduz USA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#website\"},\"description\":\"Compra agujas para m\u00e1quinas de coser industriales y familiares en Miami. Agujas Singer, Juki, Brother y m\u00e1s con env\u00edos r\u00e1pidos en USA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/categoria-producto\\\/repuestos-de-maquinas-de-coser\\\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/categoria-producto\\\/repuestos-de-maquinas-de-coser\\\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/orduz-usa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"repuestos de maquinas de coser\",\"item\":\"https:\\\/\\\/orduz-usa.com\\\/categoria-producto\\\/repuestos-de-maquinas-de-coser\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agujas para M\u00e1quinas de Coser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#website\",\"url\":\"https:\\\/\\\/orduz-usa.com\\\/\",\"name\":\"orduzcolombia\",\"description\":\"Maquinas de Coser INDUSTRIALES Y FAMILIARES\",\"publisher\":{\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#organization\"},\"alternateName\":\"Maquinas de Coser Orduz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orduz-usa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#organization\",\"name\":\"Orduz Colombia\",\"alternateName\":\"Maquinas de Coser Orduz\",\"url\":\"https:\\\/\\\/orduz-usa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/orduzcolombia.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-orduz-isotipo.jpg?fit=269%2C259&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/orduzcolombia.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-orduz-isotipo.jpg?fit=269%2C259&ssl=1\",\"width\":269,\"height\":259,\"caption\":\"Orduz Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/orduz-usa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Industrial Sewing Machine Needles | Orduz USA","description":"Buy industrial and family sewing machine needles in Miami. Singer, Juki, Brother and more needles with fast shipping in USA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orduz-usa.com\/en\/product-category\/sewing-machine-parts\/orduz-usa-com-product-category-sewing-machine-needles\/","og_locale":"en_US","og_type":"article","og_title":"Agujas para M\u00e1quinas de Coser archivos","og_description":"Compra agujas para m\u00e1quinas de coser industriales y familiares en Miami. Agujas Singer, Juki, Brother y m\u00e1s con env\u00edos r\u00e1pidos en USA.","og_url":"https:\/\/orduz-usa.com\/en\/product-category\/sewing-machine-parts\/orduz-usa-com-product-category-sewing-machine-needles\/","og_site_name":"Orduz USA Maquinas de coser","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/orduz-usa.com\/categoria-producto\/repuestos-de-maquinas-de-coser\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\/","url":"https:\/\/orduz-usa.com\/categoria-producto\/repuestos-de-maquinas-de-coser\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\/","name":"Industrial Sewing Machine Needles | Orduz USA","isPartOf":{"@id":"https:\/\/orduz-usa.com\/#website"},"description":"Buy industrial and family sewing machine needles in Miami. Singer, Juki, Brother and more needles with fast shipping in USA.","breadcrumb":{"@id":"https:\/\/orduz-usa.com\/categoria-producto\/repuestos-de-maquinas-de-coser\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/orduz-usa.com\/categoria-producto\/repuestos-de-maquinas-de-coser\/orduz-usa-com-categoria-producto-agujas-maquinas-coser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/orduz-usa.com\/"},{"@type":"ListItem","position":2,"name":"repuestos de maquinas de coser","item":"https:\/\/orduz-usa.com\/categoria-producto\/repuestos-de-maquinas-de-coser\/"},{"@type":"ListItem","position":3,"name":"Agujas para M\u00e1quinas de Coser"}]},{"@type":"WebSite","@id":"https:\/\/orduz-usa.com\/#website","url":"https:\/\/orduz-usa.com\/","name":"orduzcolombia","description":"INDUSTRIAL AND FAMILY SEWING MACHINES","publisher":{"@id":"https:\/\/orduz-usa.com\/#organization"},"alternateName":"Maquinas de Coser Orduz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orduz-usa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/orduz-usa.com\/#organization","name":"Orduz Colombia","alternateName":"Maquinas de Coser Orduz","url":"https:\/\/orduz-usa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/orduz-usa.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/orduzcolombia.com\/wp-content\/uploads\/2024\/10\/logo-orduz-isotipo.jpg?fit=269%2C259&ssl=1","contentUrl":"https:\/\/i0.wp.com\/orduzcolombia.com\/wp-content\/uploads\/2024\/10\/logo-orduz-isotipo.jpg?fit=269%2C259&ssl=1","width":269,"height":259,"caption":"Orduz Colombia"},"image":{"@id":"https:\/\/orduz-usa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/orduz-usa.com\/en\/wp-json\/wp\/v2\/product_cat\/5499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orduz-usa.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/orduz-usa.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/orduz-usa.com\/en\/wp-json\/wp\/v2\/product_cat\/5357"}],"wp:post_type":[{"href":"https:\/\/orduz-usa.com\/en\/wp-json\/wp\/v2\/product?product_cat=5499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}